{"id":118265,"date":"2019-11-03T08:26:15","date_gmt":"2019-11-03T13:26:15","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=118265"},"modified":"2019-11-03T08:34:05","modified_gmt":"2019-11-03T13:34:05","slug":"alegan-wwe-ha-mentido-en-la-historia-de-problemas-con-vuelo-de-arabia-saudita","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/alegan-wwe-ha-mentido-en-la-historia-de-problemas-con-vuelo-de-arabia-saudita\/","title":{"rendered":"Alegan WWE minti\u00f3 en la historia de problemas con vuelo de Arabia Saud\u00edta"},"content":{"rendered":"<p>Las superestrellas de la WWE no pudieron salir de Arabia Saudita por 24 horas despu\u00e9s de Crown Jewel, pero la historia detr\u00e1s de lo sucedido parece ser m\u00e1s complicada de lo que luce. <!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><br \/>\nDave Meltzer mencion\u00f3 hoy durante <a href=\"http:\/\/www.f4wonline.com\" target=\"_blank\" rel=\"noopener\">Wrestling Observer Radio<\/a> que la historia publicada por WWE sobre el primer vuelo ch\u00e1rter que sali\u00f3 de Arabia Saudita es &#8220;una completa mentira&#8221;. La historia dec\u00eda que \u201cciertas Superestrellas se vieron tan motivadas a llegar a SmackDown que juntaron su dinero y consiguieron un vuelo\u201d.<\/p>\n<p>Eso alegadamente fue una mentira porque fue WWE quien pag\u00f3 el vuelo, e hizo a las superestrellas que se quedaron varadas en el pa\u00eds lucir mal. Algunos de estos luchadores han hecho referencia de manera ir\u00f3nica en las redes sociales a \u201cTop 20\u201d, en referencia a las primeras 20 personas que s\u00ed pudieron salir.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Not the <a href=\"https:\/\/twitter.com\/hashtag\/Top20?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Top20<\/a>?&#x1f595;&#x1f3fb;I\u2019m #1 at home! We don\u2019t leave each other behind. <a href=\"https:\/\/twitter.com\/WWE?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@WWE<\/a> <a href=\"https:\/\/t.co\/Cbj3XUV6VT\">pic.twitter.com\/Cbj3XUV6VT<\/a><\/p>\n<p>&mdash; Joe Hennig (@RealCurtisAxel) <a href=\"https:\/\/twitter.com\/RealCurtisAxel\/status\/1190809320059023362?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 3, 2019<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\nMeltzer adem\u00e1s dice que con excepci\u00f3n de un talento, todos con los que habl\u00f3 opinan que el alegado desperfecto en el avi\u00f3n no era cierto ya que debido a sus experiencias volando el mundo saben c\u00f3mo este tipo de situaci\u00f3n luce en el \u00e1rea y este no era el caso aqu\u00ed. <\/p>\n<p>El rumor rondando es que Arabia Saudita le debe dinero a la WWE y la situaci\u00f3n del avi\u00f3n estuvo relacionado a esta disputa. Ninguna de las partes ha comentado sobre el particular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las superestrellas de la WWE no pudieron salir de Arabia Saudita por 24 horas despu\u00e9s de Crown Jewel, pero la historia detr\u00e1s de lo sucedido parece ser m\u00e1s complicada de lo que luce.<\/p>\n","protected":false},"author":1,"featured_media":118266,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[9],"class_list":["post-118265","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe","tag-wwe"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/118265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=118265"}],"version-history":[{"count":3,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/118265\/revisions"}],"predecessor-version":[{"id":118270,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/118265\/revisions\/118270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/118266"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=118265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=118265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=118265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}