{"id":118336,"date":"2019-11-05T14:59:27","date_gmt":"2019-11-05T19:59:27","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=118336"},"modified":"2019-11-05T14:59:27","modified_gmt":"2019-11-05T19:59:27","slug":"corey-graves-menciona-dos-luchadores-que-pueden-ser-mejor-utilizados-en-wwe","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/corey-graves-menciona-dos-luchadores-que-pueden-ser-mejor-utilizados-en-wwe\/","title":{"rendered":"Corey Graves menciona dos luchadores que pueden ser mejor utilizados en WWE"},"content":{"rendered":"<p>El presentador Corey Graves se tom\u00f3 un tiempo dentro de su podcast After the Bell para hablar sobre dos superestrellas de la WWE que siente que no est\u00e1n recibiendo el reconocimiento y el tiempo de televisi\u00f3n que se merecen.<!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><br \/>\n&#8220;En mi opini\u00f3n, Cesaro es la superestrella m\u00e1s subestimada, la superestrella menos utilizada, no solo en la WWE sino en toda la industria de la lucha libre&#8221;, afirm\u00f3 Graves. &#8220;Conozco a Cesaro por cerca de quince a\u00f1os. Recuerdo cuando vino a los Estados Unidos y sol\u00eda luchar con ropa de negocios, camisa de vestir, mangas cortadas y corbata. Hab\u00eda algo en \u00e9l; todo sobre Cesaro es este negocio. Siempre lo decimos sobre Randy Orton: si fueras a dise\u00f1ar un luchador desde cero, para m\u00ed, Cesaro es algo as\u00ed.<\/p>\n<p>Si hay alguna raz\u00f3n espec\u00edfica por la que Cesaro no ha recibido un impulso a nivel del evento estelar, Graves cree que podr\u00eda tener que ver con su trabajo de promoci\u00f3n en el micr\u00f3fono. <\/p>\n<p>&#8220;Supongo que es porque no es necesariamente convincente en el micr\u00f3fono&#8221;, admiti\u00f3 Graves. &#8220;Una vez m\u00e1s, \u00e9l ser\u00e1 el primero en admitirte eso. No quiero escuchar a Cesaro dar una diatriba de cinco minutos detr\u00e1s del escenario o en el ring para dar comienzo a RAW o SmackDown. Supongo que quiz\u00e1s es por eso que no est\u00e1 obteniendo las oportunidades de ser &#8216;The Guy&#8217;.<\/p>\n<p>Graves tambi\u00e9n es franco sobre su afinidad por el ex campe\u00f3n de peso crucero de la WWE, Drew Gulak.<br \/>\n<!-- Shortcode [b] does not exist --><br \/>\n Corey elogi\u00f3 el estilo de lucha de Drew y su trabajo de promo, mencionando que las presentaciones de PowerPoint de Drew no le han permitido brillar realmente en el micr\u00f3fono como Graves sabe que puede.<\/p>\n<p>&#8220;Otro tipo que creo que no est\u00e1 recibiendo lo que le corresponde, pero creo que lo har\u00e1 a tiempo es Drew Gulak. Gulak es diferente, es un luchador en el ring. Cuando suena la campana, Gulak lucha y es diferente&#8221;, explic\u00f3 Corey. &#8220;Su presentaci\u00f3n, la forma en que se ocupa de las cosas en el ring, [es] otro que si se le da el escenario correcto y no es asesinado por Braun Strowman, o por Lucha House Party, o por quien sea esa semana, Gulak puede hablar.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presentador Corey Graves se tom\u00f3 un tiempo dentro de su podcast After the Bell para hablar sobre dos superestrellas de la WWE que siente que no est\u00e1n recibiendo el reconocimiento y el tiempo de televisi\u00f3n que se merecen.<\/p>\n","protected":false},"author":1,"featured_media":118337,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[9],"class_list":["post-118336","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-wwe"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/118336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=118336"}],"version-history":[{"count":1,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/118336\/revisions"}],"predecessor-version":[{"id":118338,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/118336\/revisions\/118338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/118337"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=118336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=118336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=118336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}