{"id":121614,"date":"2020-02-28T06:10:01","date_gmt":"2020-02-28T11:10:01","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=121614"},"modified":"2020-02-28T11:20:40","modified_gmt":"2020-02-28T16:20:40","slug":"goldberg-le-dice-idiota-a-actor-de-home-alone-tras-critica","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/goldberg-le-dice-idiota-a-actor-de-home-alone-tras-critica\/","title":{"rendered":"Goldberg le dice &#8220;idiota&#8221; a actor de &#8220;Home Alone&#8221; tras cr\u00edtica"},"content":{"rendered":"<p>Como vimos en Super ShowDown, Goldberg logr\u00f3 vencer a Bray Wyatt para comenzar su segundo reinado como campe\u00f3n Universal.<!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><br \/>\nA muchos fan\u00e1ticos no le agrad\u00f3 el resultado, incluyendo al actor y fan\u00e1tico de la lucha libre Macaulay Culkin, mejor recordado por sus filmes de \u201cHome Alone\u201d, quien reaccion\u00f3 al resultado en las redes sociales se\u00f1alando que hab\u00eda cancelado sus boletos para Tampa Bay (WrestleMania) a causa de lo sucedido.<\/p>\n<p>\u201cAcabo de cancelar mis boletos para Tampa Bay,\u201d dijo Culkin.<\/p>\n<p>Goldberg vio el \u201cTweet\u201d y le respondi\u00f3: \u201cDebidamente anotado idiota\u201d<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\"><a href=\"https:\/\/twitter.com\/IncredibleCulk?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@IncredibleCulk<\/a> duly noted dork &#x1f44d;&#x1f621;<\/p>\n<p>\u2014 Bill Goldberg (@Goldberg) <a href=\"https:\/\/twitter.com\/Goldberg\/status\/1233283499848851456?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 28, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\nGoldberg nunca ha sido t\u00edmido cuando se trata de dejar que los fan\u00e1ticos sepan lo que realmente piensa, y como hemos visto desde su reciente retorno, ha discutido con otros cr\u00edticos de su desempe\u00f1o, como sucedi\u00f3 con Matt Riddle.<\/p>\n<h2><strong>Goldberg &#8220;saldr\u00e1 cojeando&#8221; luego de victoria<\/strong><\/h2>\n<p>Bill Goldberg habl\u00f3 con las c\u00e1maras de WWE despu\u00e9s de su victoria sobre &#8220;The Fiend&#8221; Bray Wyatt en Super ShowDown.<br \/>\n<!-- Shortcode [b] does not exist --><br \/>\n&#8220;Lo primero, saldr\u00e9 cojeando de Arabia Saudita&#8221;, dijo Goldberg cuando se le pregunt\u00f3 sobre sus reacciones ante la victoria por el t\u00edtulo. &#8220;Pero bueno, es un honor estar aqu\u00ed y poder salir y obtener este cintur\u00f3n de nuevo, este t\u00edtulo de nuevo. Es un sue\u00f1o hecho realidad, realmente lo es.<\/p>\n<p>&#8220;Es algo a lo que siempre te diriges, pero cuanto m\u00e1s viejo te haces, m\u00e1s lejos crees que ese pin\u00e1culo est\u00e1 lejos, y yo solo &#8230; Estoy asombrado&#8221;. Tuve que golpearlo con todo lo que ten\u00eda, tan r\u00e1pido como tuve, tan r\u00e1pido como pude. Sorpr\u00e9ndelo, t\u00f3marlo desprevenido, como hice con Brock Lesnar. Sabes, debes golpear a los luchadores antes de que est\u00e9n listos, especialmente a mi edad. As\u00ed que funcion\u00f3, lo considerar\u00e9 como otra conquista,&#8221; dijo.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/cpP5kcQ1ORw\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como vimos en Super ShowDown, Goldberg logr\u00f3 vencer a Bray Wyatt para comenzar su segundo reinado como campe\u00f3n Universal.<\/p>\n","protected":false},"author":1,"featured_media":121631,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[1361,9],"class_list":["post-121614","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe","tag-goldberg","tag-wwe"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/121614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=121614"}],"version-history":[{"count":4,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/121614\/revisions"}],"predecessor-version":[{"id":121619,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/121614\/revisions\/121619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/121631"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=121614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=121614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=121614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}