{"id":126425,"date":"2020-08-05T22:30:20","date_gmt":"2020-08-06T02:30:20","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=126425"},"modified":"2020-08-05T22:35:38","modified_gmt":"2020-08-06T02:35:38","slug":"reporte-nxt-8-5-mcafee-deja-maltrecho-a-cole","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/reporte-nxt-8-5-mcafee-deja-maltrecho-a-cole\/","title":{"rendered":"Reporte NXT 8\/5 &#8211; McAfee deja maltrecho a Cole"},"content":{"rendered":"<p>El programa comienza con la lucha para decidir la pr\u00f3xima contendiente por el Campeonato Femenino NXT.<!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><br \/>\nDakota Kai derrot\u00f3 a Rhea Ripley despu\u00e9s de la interferencia de Mercedes Mart\u00ednez.<\/p>\n<p>Bronson Reed derrot\u00f3 a Shane Thorne<\/p>\n<p>Breezango lleg\u00f3 a la arena y fueron atacados por El Legado del Fantasma, luego secuestraron a Fandango.<\/p>\n<p>McKenzie Mitchell entrevist\u00f3 a The Robert Stone Brand. Robert Stone dijo que Ripley puede haber terminado con ellos, pero no han terminado con ella.<\/p>\n<p>Damian Priest derrot\u00f3 a Oney Lorcan y Ridge Holland en triple amenaza clasificatoria por el campeonato de Norteam\u00e9rica.<\/p>\n<p>Keith Lee derrot\u00f3 a Cameron Grimes.<\/p>\n<p>Las luces de la arena se apagaron y la voz de Scarlett se oye. Karrion Kross luego apareci\u00f3 en una pantalla de video con un mensaje para Lee. Kross hab\u00eda atacado a varios luchadores. El mensaje fue que quiere una pelea por el t\u00edtulo.<\/p>\n<p>William Regal anunci\u00f3 que Dexter Lumis sufri\u00f3 una lesi\u00f3n en el tobillo y\u00a0 est\u00e1 fuera de la lucha de escalera en TakeOver. Como ni Johnny Gargano ni Finn Balor perdieron en sus clasificatorios, ambos quieren consideraci\u00f3n. Tambi\u00e9n est\u00e1 Ridge Holland en el programa de esta noche que perdi\u00f3 sin perder una ca\u00edda. Por lo tanto, dentro de dos semanas, los tres luchadores un cuarto de la otra lucha se enfrentar\u00e1n en dos luchas individuales.<br \/>\n<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\"><p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Responsive sc c -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"4234005358\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/p><\/div><br \/>\nEl Legado del Fantasma arrastr\u00f3 un indefenso Fandango a la arena. Escobar estaba enojado porque Fandango y Tyler Breeze se burlaban de su cultura. Ra\u00fal Mendoza y Joaqu\u00edn Wilde fueron a golpear a Fandango cuando Breeze entr\u00f3 corriendo pero tambi\u00e9n fue atacado y golpeado. Escobar tambi\u00e9n emiti\u00f3 una advertencia a Isaiah &#8220;Swerve&#8221; Scott.<\/p>\n<p>Pat McAfee se uni\u00f3 a la cabina de transmisi\u00f3n.<\/p>\n<p>Tegan Nox derrot\u00f3 a Indi Hartwell.<\/p>\n<p>En la estelar, Imperium retuvieron los campeonatos en pareja ante Undisputed Era cuando Adam Cole en las afueras se acerca a McAfee y le dice que puede escucharlo. McAfee dice que solo estaba bromeando. Cole se va, pero McAfee lo llama un peque\u00f1o duende enojado y le lanza agua de una botella a la cara y al pecho de Cole. Los funcionarios se interponen entre ellos, incluidos Triple H y Shawn Michaels. O\u2019Reilly y Fish se distraen con esto para ser vencidos.<\/p>\n<p>Despues, McAfee y Cole todav\u00eda discuten hasta que McAfee se va. Cole est\u00e1 furioso y quiere pelear. McAfee aprovecha el hecho de que Cole est\u00e1 en la mesa y corre y le pega una gran patada en la cara. Los funcionarios ordenan a McAfee que salga de la arena mientras grita sobre lo poco profesional que es este lugar. Cole se muestra tendido, boca abajo. Michaels llama a un m\u00e9dico y verifica a Cole cuando NXT sale del aire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa comienza con la lucha para decidir la pr\u00f3xima contendiente por el Campeonato Femenino NXT.<\/p>\n","protected":false},"author":3,"featured_media":126426,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[1467],"class_list":["post-126425","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe","tag-nxt"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/126425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=126425"}],"version-history":[{"count":3,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/126425\/revisions"}],"predecessor-version":[{"id":126430,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/126425\/revisions\/126430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/126426"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=126425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=126425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=126425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}