{"id":130336,"date":"2021-03-14T19:04:33","date_gmt":"2021-03-14T23:04:33","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=130336"},"modified":"2021-03-14T19:05:31","modified_gmt":"2021-03-14T23:05:31","slug":"wwe-tendra-las-asistencias-mas-grandes-para-un-show-post-pandemia","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/wwe-tendra-las-asistencias-mas-grandes-para-un-show-post-pandemia\/","title":{"rendered":"Wrestlemania tendr\u00e1 las asistencias m\u00e1s grandes para un show post-pandemia"},"content":{"rendered":"<p>A principios de esta semana se inform\u00f3 que los oficiales de la WWE esperaban tener 45,000 fan\u00e1ticos en cada noche de WrestleMania 37 en el Estadio Raymond James en Tampa, Florida.<!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><br \/>\nJon Alba de Spectrum Sports 360 ha confirmado que WWE quiere traer 45,000 cada noche, lo que ser\u00eda la multitud m\u00e1s grande en un evento deportivo o de entretenimiento desde que comenz\u00f3 la pandemia el a\u00f1o pasado.<\/p>\n<p>&#8220;Puedo confirmar de forma independiente los informes que #WWE apunta a unas 45,000 personas por noche en el Estadio Raymond James para #WrestleMania, que ser\u00eda, por mucho, la mayor multitud en un evento deportivo o de entretenimiento en Estados Unidos desde que comenz\u00f3 la pandemia&#8221;, escribi\u00f3 Alba.<br \/>\n<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\"><p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Responsive sc c -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"4234005358\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/p><\/div><br \/>\n\u201cMe comuniqu\u00e9 con la Autoridad de Deportes de Tampa Bay, que administra el Estadio Raymond James, pero a\u00fan no he recibido respuesta. Los boletos est\u00e1n a la venta el 16 de marzo, aunque no se ha dicho p\u00fablicamente cu\u00e1ntos estar\u00e1n disponibles. El gobernador de Florida Ron DeSantis firm\u00f3 una orden ejecutiva el oto\u00f1o pasado que permite que los estadios funcionen a plena capacidad si as\u00ed lo desean, pero nadie ha realizado un espect\u00e1culo de esa magnitud hasta ahora &#8220;.<\/p>\n<p>Los \u00fanicos combates confirmados hasta ahora son Roman Reigns vs. Edge y Sasha Banks vs. Bianca Belair.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A principios de esta semana se inform\u00f3 que los oficiales de la WWE esperaban tener 45,000 fan\u00e1ticos en cada noche de WrestleMania 37 en el Estadio Raymond James en Tampa, Florida.<\/p>\n","protected":false},"author":1,"featured_media":122162,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[9],"class_list":["post-130336","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe","tag-wwe"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/130336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=130336"}],"version-history":[{"count":3,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/130336\/revisions"}],"predecessor-version":[{"id":130340,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/130336\/revisions\/130340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/122162"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=130336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=130336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=130336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}