{"id":130387,"date":"2021-03-18T15:01:31","date_gmt":"2021-03-18T19:01:31","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=130387"},"modified":"2021-10-20T14:34:35","modified_gmt":"2021-10-20T18:34:35","slug":"michaels-se-disculpa-por-lucha-de-crown-jewel-bischoff-al-hof","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/michaels-se-disculpa-por-lucha-de-crown-jewel-bischoff-al-hof\/","title":{"rendered":"Michaels se disculpa por lucha de Crown Jewel; Bischoff al HOF"},"content":{"rendered":"<p>El miembro del Sal\u00f3n de la Fama de la WWE, Shawn Michaels, sali\u00f3 de su retiro para Crown Jewel 2018, donde se uni\u00f3 con Triple H y se enfrent\u00f3 a Kane y The Undertaker.<!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- 300x250 sc a -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"8592682546\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/center>\r\n<\/p><\/div><br \/>\nMientras era entrevistado por el New York Post, Michaels habl\u00f3 sobre esa lucha cual fue criticada por muchos y fue sincero al decir que no fue una buena idea.<\/p>\n<p>&#8220;No ten\u00eda idea de que, desde el punto de vista de Mark, \u00e9l lo estaba viendo como si fuera uno de los (encuentros) que podr\u00eda alejarse &#8220;.<\/p>\n<p>\u201cPara m\u00ed, lo fue [divertido]. Fue solo una oportunidad de estar con mis amigos &#8220;.<\/p>\n<p>&#8220;Todo lo que puedo hacer es que me disculpo con los chicos,\u201d dijo Michaels.<\/p>\n<h2>Eric Bischoff anunciado para el Hall of Fame<\/h2>\n<p><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\"><p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Responsive sc c -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"4234005358\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/p><\/div><br \/>\nWWE hizo el anuncio oficial hoy:<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">BREAKING: As first announced on <a href=\"https:\/\/twitter.com\/AfterTheBellWWE?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@AfterTheBellWWE<\/a>, <a href=\"https:\/\/twitter.com\/EBischoff?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@EBischoff<\/a> is the latest inductee in the WWE Hall of Fame\u2019s Class of 2021! <a href=\"https:\/\/twitter.com\/hashtag\/WWEHOF?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#WWEHOF<\/a> <a href=\"https:\/\/t.co\/DTT5JiSBQ2\">https:\/\/t.co\/DTT5JiSBQ2<\/a><\/p>\n<p>\u2014 WWE (@WWE) <a href=\"https:\/\/twitter.com\/WWE\/status\/1372521122659500033?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 18, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El miembro del Sal\u00f3n de la Fama de la WWE, Shawn Michaels, sali\u00f3 de su retiro para Crown Jewel 2018, donde se uni\u00f3 con Triple H y se enfrent\u00f3 a Kane y The Undertaker.<\/p>\n","protected":false},"author":1,"featured_media":107944,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[7303,9],"class_list":["post-130387","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe","tag-crown-jewel","tag-wwe"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/130387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=130387"}],"version-history":[{"count":1,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/130387\/revisions"}],"predecessor-version":[{"id":130388,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/130387\/revisions\/130388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/107944"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=130387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=130387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=130387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}