{"id":183759,"date":"2022-09-11T10:31:51","date_gmt":"2022-09-11T14:31:51","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=183759"},"modified":"2022-09-11T10:31:51","modified_gmt":"2022-09-11T14:31:51","slug":"seth-rollins-me-senti-muy-menospreciado-por-no-tener-un-combate-en-summerslam","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/seth-rollins-me-senti-muy-menospreciado-por-no-tener-un-combate-en-summerslam\/","title":{"rendered":"Seth Rollins: &#8220;Me sent\u00ed muy menospreciado&#8221; por no tener un combate en SummerSlam"},"content":{"rendered":"<p>Seth Rollins estaba ansioso por competir en SummerSlam antes de que su lucha fuera cancelada este a\u00f1o.<!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><br \/>\nRollins Riddle estaban inicialmente programados para luchar en el evento m\u00e1s popular del verano de la WWE. Sin embargo, WWE anunci\u00f3 m\u00e1s tarde que el combate se pospuso debido a una lesi\u00f3n.<\/p>\n<p>Rollins se disculp\u00f3 por la cancelaci\u00f3n del combate, citando su decepci\u00f3n por la decisi\u00f3n.<\/p>\n<p>\u201cPara cualquiera que haya comprado un boleto para #SummerSlam con la esperanza de verme en acci\u00f3n, me disculpo. Hice todo lo que pude durante los \u00faltimos 6 meses para ganar mi lugar en este programa, pero algunas cosas est\u00e1n fuera de mi control. Gracias por cantar siempre mi canci\u00f3n. Te escuchar\u00e1n alg\u00fan d\u00eda\u201d, escribi\u00f3 Rollins a trav\u00e9s de Twitter.<br \/>\n<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\"><p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Responsive sc c -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"4234005358\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/p><\/div><br \/>\nEn una aparici\u00f3n reciente en <a href=\"https:\/\/open.spotify.com\/episode\/0n4hEyMg67O7wjxlxssNI9\" target=\"_blank\" rel=\"noopener\">Out of Character<\/a> con Ryan Satin, Rollins habl\u00f3 con franqueza sobre su decepci\u00f3n con el aplazamiento de la lucha. Rollins coment\u00f3s sobre lo que habl\u00f3 con Triple H sobre el asunto y el tweet de respuesta de Hunter a sus comentarios (\u201cte escuchamos\u201d).<\/p>\n<p>Rollins explic\u00f3 que se sinti\u00f3 &#8220;despreciado&#8221; por la decisi\u00f3n, a pesar de su impresionante trabajo durante el \u00faltimo a\u00f1o.<\/p>\n<p>\u201cTodav\u00eda tengo un chip en mi hombro todo el tiempo, sigo pensando que estoy compitiendo a un nivel tan alto en este momento que nadie puede tocar. No me importa si eres Brock Lesnar o Roman Reigns o Logan Paul, Pat McAfee fuera de nuestra industria, simplemente pens\u00e9 que nadie merec\u00eda estar en esa cartelera m\u00e1s que yo\u201d.<br \/>\n<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><br \/>\n\u201cTrabaj\u00e9 demasiado con la historia de Cody [Rhodes], con la historia de Edge, con la historia de Roman, y todo lo que estaba tocando estaba en las nubes\u201d, explic\u00f3. \u201cEstaba tan bien, estaba en una zona. Entonces, me sent\u00ed muy menospreciado y no estaba dispuesto a dejar que nadie m\u00e1s controlara esa narrativa. Entonces, me sent\u00ed mal, pero ten\u00eda que hacer lo que ten\u00eda que hacer\u201d.<\/p>\n<p>\u201cHunter (Triple H) ha estado en ambos lados por suerte. Entonces, \u00e9l entendi\u00f3 eso. Y tuvimos una conversaci\u00f3n despu\u00e9s y todo est\u00e1 bien. Pero s\u00ed, a veces simplemente no puedo, no puedo dejar que alguien me presione. Soy mucho un jugador de equipo. Entiendo mucho el lado comercial de las cosas. Entiendo que no todo se trata de m\u00ed. Y entiendo todo eso, pero a veces me vencen como dos veces al a\u00f1o solo por un momento en toda regla como &#8220;qu\u00e9 diablos&#8221;.<\/p>\n<p>A pesar de la cancelaci\u00f3n del combate de SummerSlam, Seth Rollins sigue agradecido por su puesto y su vida en la WWE.<\/p>\n<p>\u201cTodo est\u00e1 bien\u201d, se\u00f1al\u00f3. \u201cMira, no quiero que nadie piense que soy un llor\u00f3n. A veces lo soy, pero al final del d\u00eda, todo es genial. Es genial. Puedo hacer el trabajo de mis sue\u00f1os, puedo viajar por el mundo con mi esposa y mi beb\u00e9. Amo a todos con los que trabajo, para quienes trabajo,\u201d dijo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seth Rollins estaba ansioso por competir en SummerSlam antes de que su lucha fuera cancelada este a\u00f1o.<\/p>\n","protected":false},"author":1,"featured_media":149723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[],"class_list":["post-183759","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/183759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=183759"}],"version-history":[{"count":1,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/183759\/revisions"}],"predecessor-version":[{"id":183760,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/183759\/revisions\/183760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/149723"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=183759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=183759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=183759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}