{"id":186406,"date":"2022-11-27T15:38:06","date_gmt":"2022-11-27T20:38:06","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=186406"},"modified":"2022-11-27T15:40:14","modified_gmt":"2022-11-27T20:40:14","slug":"critican-a-ronda-rousey-escapar-a-la-lucha-libre-y-no-regresar-al-mma","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/critican-a-ronda-rousey-escapar-a-la-lucha-libre-y-no-regresar-al-mma\/","title":{"rendered":"Critican a Ronda Rousey por &#8220;escapar&#8221; a la lucha libre y no regresar al MMA"},"content":{"rendered":"<p>Ronda Rousey disfrut\u00f3 de una carrera hist\u00f3rica durante su permanencia en el <a href=\"http:\/\/ufc.com\" target=\"_blank\" rel=\"noopener\">UFC<\/a>.<!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><br \/>\nSe convirti\u00f3 en la primera mujer en firmar con la compa\u00f1\u00eda y tambi\u00e9n se convirti\u00f3 en la primera mujer en tener un t\u00edtulo de UFC.<\/p>\n<p>Sin embargo, todo eso se vino abajo cuando se enfrent\u00f3 a Holly Holm en UFC 193 al derrotarla por nocaut. Despu\u00e9s de la derrota, Rousey se alej\u00f3 un a\u00f1o del deporte, pero regres\u00f3 a UFC 207 para enfrentarse a Amanda Nunes. Sin embargo, Rousey tambi\u00e9n perdi\u00f3 esa pelea. Esa fue la \u00faltima pelea de Rousey y luego firm\u00f3 con WWE en 2017.<\/p>\n<p>La ex campeona de peso gallo de UFC, Julianna Pena, tuvo algunas palabras duras para Ronda Rousey durante su aparici\u00f3n en <a href=\"https:\/\/www.youtube.com\/watch?v=6XykbxRDFhA\" target=\"_blank\" rel=\"noopener\">MMA Hour<\/a> . Cuestion\u00f3 la legitimidad de Rousey y dijo que WWE fue su refugio.<\/p>\n<p>\u201cRonda es una noticia tan vieja. Lo incre\u00edble de ella es que abri\u00f3 la puerta y estaba destrozando gente en diez segundos y se convirti\u00f3 en una estrella porque estaba destrozando gente en el primer asalto y eso es genial.<br \/>\n<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\"><p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Responsive sc c -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"4234005358\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/p><\/div><br \/>\n&#8220;Pero fue noqueada dos veces y nunca volvi\u00f3, as\u00ed que, \u00bfqu\u00e9 tan leg\u00edtima es? Tuvo que ir a la lucha libre profesional y lo entiendo, es genial, pero como peleadora y alguien que es competitiva, s\u00e9 que en el fondo probablemente\u00a0 le molesta que haya escapado de dos derrotas por nocaut y nunca haya regresado para hacer que su nombre se restableciera.\u201d<\/p>\n<p>Desde que se uni\u00f3 a la WWE, Rousey ha llegado a la cima y se ha convertido en tres veces campeona femenina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ronda Rousey disfrut\u00f3 de una carrera hist\u00f3rica durante su permanencia en el UFC.<\/p>\n","protected":false},"author":1,"featured_media":112495,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[],"class_list":["post-186406","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/186406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=186406"}],"version-history":[{"count":2,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/186406\/revisions"}],"predecessor-version":[{"id":186409,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/186406\/revisions\/186409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/112495"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=186406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=186406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=186406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}