{"id":191637,"date":"2023-01-06T19:18:56","date_gmt":"2023-01-07T00:18:56","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=191637"},"modified":"2023-01-06T19:18:56","modified_gmt":"2023-01-07T00:18:56","slug":"ric-flair-dice-muchos-talentos-de-la-wwe-no-sigue-sus-consejos","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/ric-flair-dice-muchos-talentos-de-la-wwe-no-sigue-sus-consejos\/","title":{"rendered":"Ric Flair dice muchos talentos de la WWE no sigue sus consejos"},"content":{"rendered":"<div>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Si bien muchos luchadores est\u00e1n agradecidos de tener varias plataformas poderosas para ayudarlos a ganar dinero, Ric Flair no aprecia tanto las redes sociales. <\/span><\/span><!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><\/p>\n<p><a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/the-hall-of-fame-with-booker-t-brad-gilmore\/id1458107908\" target=\"_blank\" rel=\"noopener\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Hablando en un episodio reciente del podcast de Booker T<\/span><\/span><\/a><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00a0<\/span><span style=\"vertical-align: inherit;\">, Ric Flair habl\u00f3 sobre la generaci\u00f3n m\u00e1s joven de luchadores que ganan m\u00e1s dinero con las redes sociales que con su talento.<\/span><\/span><\/p>\n<blockquote class=\"wp-block-quote\"><p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u201cEn este momento, hay m\u00e1s jovenes que ganan dinero gracias a sus redes sociales que a su talento. <\/span><span style=\"vertical-align: inherit;\">Es una locura absoluta. <\/span><span style=\"vertical-align: inherit;\">Quiero decir, las redes sociales pueden hacer o deshacer a cualquiera, y ahora tienen jovenes que ganan millones de d\u00f3lares que ni siquiera podr\u00edan caminar en el maldito ring conmigo y Book. <\/span><span style=\"vertical-align: inherit;\">Lo juro por Dios, no podr\u00edan luchar 30 minutos si tuvieran que hacerlo todos los d\u00edas. <\/span><span style=\"vertical-align: inherit;\">\u00bfTiene sentido? <\/span><span style=\"vertical-align: inherit;\">No cada dos d\u00edas, todos los d\u00edas\u201d, dijo Flair.<\/span><\/span><\/p><\/blockquote>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Durante el mismo episodio de podcast, Flair tambi\u00e9n habl\u00f3 sobre el talento m\u00e1s joven que no quiere consejos de veteranos como \u00e9l.<\/span><\/span><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\"><p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Responsive sc c -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"4234005358\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/p><\/div><\/p>\n<blockquote class=\"wp-block-quote\"><p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u201cBueno, he aprendido mi lecci\u00f3n. <\/span><span style=\"vertical-align: inherit;\">No hace ning\u00fan bien. <\/span><span style=\"vertical-align: inherit;\">Quiero decir, la gente luego dice: &#8216;Es un imb\u00e9cil&#8217;. <\/span><span style=\"vertical-align: inherit;\">No ayudar\u00e1 a nadie. <\/span><span style=\"vertical-align: inherit;\">A todos les he dado consejos, y la gente ha sido muy educada al preguntarme 100 veces, especialmente cuando viajaba mucho con Ashley, los j\u00f3venes. <\/span><span style=\"vertical-align: inherit;\">Ellos toman mi opini\u00f3n, que j#didamente s\u00e9 muy bien de lo que estoy hablando, y luego se suben al auto, o suben la rampa, y miran y ven lo que dicen los fans al respecto, o hablan con otro tipo que tiene tanta experiencia como \u00e9l o menos, y eso es lo que hacen. <\/span><span style=\"vertical-align: inherit;\">Dios lo sabe, s\u00e9 algo. <\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Podr\u00eda criticar estos encuentros, pero no vale la pena el agravamiento, n\u00famero uno. <\/span><span style=\"vertical-align: inherit;\">N\u00famero dos, mi hija trabaja all\u00ed. <\/span><span style=\"vertical-align: inherit;\">No voy a decir nada excepto cosas positivas\u201d.<\/span><\/span><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si bien muchos luchadores est\u00e1n agradecidos de tener varias plataformas poderosas para ayudarlos a ganar dinero, Ric Flair no aprecia tanto las redes sociales.<\/p>\n","protected":false},"author":1,"featured_media":133864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[],"class_list":["post-191637","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/191637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=191637"}],"version-history":[{"count":3,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/191637\/revisions"}],"predecessor-version":[{"id":191642,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/191637\/revisions\/191642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/133864"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=191637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=191637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=191637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}