{"id":191734,"date":"2023-01-07T17:44:14","date_gmt":"2023-01-07T22:44:14","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=191734"},"modified":"2023-01-07T17:44:14","modified_gmt":"2023-01-07T22:44:14","slug":"jim-cornette-dice-vince-mcmahon-regreso-para-recibir-el-cheque-de-la-venta-de-wwe","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/jim-cornette-dice-vince-mcmahon-regreso-para-recibir-el-cheque-de-la-venta-de-wwe\/","title":{"rendered":"Jim Cornette dice Vince McMahon regres\u00f3 para recibir el cheque de la venta de WWE"},"content":{"rendered":"<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">La noticia m\u00e1s importante en el mundo de la lucha libre profesional en este momento es el regreso de Vince McMahon a la Junta Directiva de la WWE y una posible venta de la compa\u00f1\u00eda.<\/span><\/span><!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Jim Cornette lanz\u00f3 un episodio adicional de su podcast Jim Cornette Experience esta semana, solo para hablar sobre McMahon. <\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Cornette sobre sus reacciones a la noticia:<\/span><\/span><\/strong><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u201cL<\/span><span style=\"vertical-align: inherit;\">a motivaci\u00f3n se reduce a una o dos cosas. <\/span><span style=\"vertical-align: inherit;\">O han tenido la intenci\u00f3n de vender la compa\u00f1\u00eda este a\u00f1o, junto con los derechos de los medios y \u00e9l dijo, &#8221;nadie va a hacer eso excepto yo&#8221; o ha decidido ahora, como lo hace Vince a menudo cuando se le ocurre una idea en la cabeza, de que este es el hacer lo correcto, que van a explorar las ventas y los derechos de los medios al mismo tiempo y nadie va a hacer eso excepto \u00e9l.<br \/>\n<\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"> <span style=\"vertical-align: inherit;\">Pero de una forma u otra, cuando alguien le entregue a otro hijo de p#ta un cheque por cinco mil millones de d\u00f3lares, ese otro hijo de p#ta que lo recibir\u00e1 ser\u00e1 Vince McMahon. <\/span><span style=\"vertical-align: inherit;\">No puedo culparlo. <\/span><span style=\"vertical-align: inherit;\">Es su cultivo, plant\u00f3 las semillas, las reg\u00f3, cultiv\u00f3 la tierra.&#8221;<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Cornette sobre si Vince deber\u00eda dirigir WWE despu\u00e9s de la venta de la empresa:<\/span><\/span><\/strong><br \/>\n<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\"><p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Responsive sc c -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"4234005358\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/p><\/div><br \/>\n<span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u201cVince todav\u00eda tiene que ser algo realista en el fondo de alguna parte. <\/span><span style=\"vertical-align: inherit;\">Si fuera m\u00e1s joven, creo que ser\u00eda casi una certeza, pero en este momento, \u00bfsolo quiere la final? para volver, las acciones van a dispararse por las nubes. <\/span><span style=\"vertical-align: inherit;\">Vamos a conseguir que esta cosa se venda. <\/span><span style=\"vertical-align: inherit;\">Alguien me va a dar cinco mil millones de d\u00f3lares y luego, boom, y estoy en lo siguiente. <\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">No s\u00e9 en este punto si \u00e9l dir\u00eda &#8221;tengo que estar a cargo&#8221;.<\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u201cDir\u00e9 ahora mismo, \u00e9l quiere el gran cheque y quiere ser responsable de la venta y quiere llevarse la gloria en este momento&#8230;<\/span><span style=\"vertical-align: inherit;\">\u201d<\/span><\/span><br \/>\n<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><br \/>\n<strong>Cornette sobre si Vince ahuyentar\u00eda a los luchadores que han regresado a la WWE:<\/strong><\/p>\n<p>\u201cBueno, creo que probablemente todos se est\u00e1n volviendo locos, pero con toda honestidad, creo que ese es el menor de sus problemas. Vince no va a volver para arreglar el pu#o creativo. Vince regresa para vender a este hijo de p#ta. Y en este a\u00f1o, revisar\u00e1n los acuerdos de derechos de los medios y tratar\u00e1n de obtener m\u00e1s dinero de quien sea&#8230;&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La noticia m\u00e1s importante en el mundo de la lucha libre profesional en este momento es el regreso de Vince McMahon a la Junta Directiva de la WWE y una posible venta de la compa\u00f1\u00eda.<\/p>\n","protected":false},"author":1,"featured_media":191772,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[],"class_list":["post-191734","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/191734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=191734"}],"version-history":[{"count":4,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/191734\/revisions"}],"predecessor-version":[{"id":191773,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/191734\/revisions\/191773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/191772"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=191734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=191734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=191734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}