{"id":203584,"date":"2023-04-15T20:26:07","date_gmt":"2023-04-16T00:26:07","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=203584"},"modified":"2023-04-15T20:26:07","modified_gmt":"2023-04-16T00:26:07","slug":"road-dogg-dice-cody-rhodes-perdio-en-wrestlemania-39-porque-no-tuvo-adversidad-en-el-camino","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/road-dogg-dice-cody-rhodes-perdio-en-wrestlemania-39-porque-no-tuvo-adversidad-en-el-camino\/","title":{"rendered":"Road Dogg dice Cody Rhodes perdi\u00f3 en WrestleMania 39 porque no tuvo adversidad en el camino"},"content":{"rendered":"<div>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Road Dogg opin\u00f3 sobre <\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">la derrota de Cody Rhodes ante Roman Reigns<\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> en WrestleMania 39.<\/span><\/span><!--more--><div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">El miembro del Sal\u00f3n de la Fama se pronunci\u00f3 sobre este tema durante el \u00faltimo episodio de su <\/span><\/span><a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/oh-you-didnt-know-with-road-dogg-brian-james-and-casio-kid\/id1616756422\" target=\"_blank\" rel=\"noopener\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">podcast Oh You Didn&#8217;t Know<\/span><\/span><\/a><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> , donde reacciona a las cr\u00edticas de que la Pesadilla Americana deber\u00eda haber destronado a Roman Reigns.<\/span><\/span><\/p>\n<blockquote><p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00bfDebi\u00f3 ganarlo (el combate)? <\/span><span style=\"vertical-align: inherit;\">No creo que sea un negocio inteligente. <\/span><span style=\"vertical-align: inherit;\">Creo que es una gran opci\u00f3n si eres fan\u00e1tico, pero no creo que sea un negocio inteligente. <\/span><span style=\"vertical-align: inherit;\">Si cuentas la historia y dices, &#8216;El final&#8217;, cierra el libro. <\/span><span style=\"vertical-align: inherit;\">Luego, &#8216;Est\u00e1 bien, ahora tenemos que empezar de nuevo&#8217;, siento que esto fue solo el cierre de un cap\u00edtulo.<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\"><p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Responsive sc c -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"4234005358\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/p><\/div><\/span><\/span><\/p><\/blockquote>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Road Dogg adem\u00e1s dijo que en realidad, Rhodes no enfrent\u00f3 ninguna adversidad desde que regres\u00f3 a la WWE en ruta a su lucha ante Reigms.<\/span><\/span><\/p>\n<blockquote><p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Entr\u00f3, y esto lo han dicho algunas personas que hablan de lucha que saben de lo que est\u00e1n hablando, entr\u00f3, y no tuvo adversidad. <\/span><span style=\"vertical-align: inherit;\">Atraves\u00f3 el Rumble, atraves\u00f3 a todos y lleg\u00f3 directamente al campe\u00f3n. <\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Entonces se podr\u00eda argumentar: &#8216;Hombre, si se lo das ahora (el campeonato), \u00bfse lo gan\u00f3?&#8217; <\/span><span style=\"vertical-align: inherit;\">Si sucede m\u00e1s adelante en su carrera, seguro, puedes contar toda esa historia, y han tratado de contar toda esa historia tanto como han podido, si ves en las promos, hablan mucho sobre lo que todo lo ha hecho porque esa es una parte realmente genial de su historia, es lo que ha logrado en esta industria p<\/span><span style=\"vertical-align: inherit;\">or s\u00ed mismo. <\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">S<\/span><span style=\"vertical-align: inherit;\">\u00ed, ha tenido algo de ayuda. <\/span><span style=\"vertical-align: inherit;\">S\u00ed, su padre era luchador, su hermano, todo eso. <\/span><span style=\"vertical-align: inherit;\">Hombre, entr\u00f3 y cambi\u00f3 un poco el juego, y lo felicito por eso.<\/span><\/span><\/p><\/blockquote>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Road Dogg opin\u00f3 sobre la derrota de Cody Rhodes ante Roman Reigns en WrestleMania 39.<\/p>\n","protected":false},"author":1,"featured_media":203586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[],"class_list":["post-203584","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/203584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=203584"}],"version-history":[{"count":2,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/203584\/revisions"}],"predecessor-version":[{"id":203588,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/203584\/revisions\/203588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/203586"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=203584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=203584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=203584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}