{"id":291523,"date":"2026-07-14T19:22:52","date_gmt":"2026-07-14T23:22:52","guid":{"rendered":"https:\/\/www.prwrestling.com\/nw\/?p=291523"},"modified":"2026-07-14T19:22:52","modified_gmt":"2026-07-14T23:22:52","slug":"keith-lee-de-aew-parece-haberse-retirado-de-la-lucha-libre-reporte","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/keith-lee-de-aew-parece-haberse-retirado-de-la-lucha-libre-reporte\/","title":{"rendered":"Keith Lee de AEW parece haberse retirado de la lucha libre &#8211; Reporte"},"content":{"rendered":"<p>No hay informaci\u00f3n definitiva sobre la situaci\u00f3n de Keith Lee, pero, dentro de la industria, se cree que podr\u00eda haber disputado ya su \u00faltimo combate.<!--more--><\/p>\n<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- 300x250 sc a -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"8592682546\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/center>\r\n<\/p><\/div>\n<p>Lee, de 41 a\u00f1os, sigue bajo contrato con <a href=\"https:\/\/www.prwrestling.com\/nw\/category\/all-elite-wrestling\/\">AEW<\/a>, pero no ha luchado desde diciembre de 2023. En aquel entonces, se vio obligado a retirarse por una lesi\u00f3n, pero en el verano de 2025 declar\u00f3 que su salud hab\u00eda sido buena durante un tiempo .<\/p>\n<p>Tras la noticia del divorcio de Lee y Mia Yim , Bryan Alvarez habl\u00f3 sobre Lee en Wrestling Observer Live y comparti\u00f3 las \u00faltimas informaciones que ha escuchado. Alvarez coment\u00f3 que, si bien \u00e9l personalmente desconoce los detalles, en el mundo de la lucha libre se cree que Lee ha terminado de competir en el ring.<\/p>\n<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\"><p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Responsive sc c -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"4234005358\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/p><\/div>\n<blockquote><p>\u201cTodo el mundo se pregunta qu\u00e9 pasa con Keith Lee. \u00bfVolver\u00e1 alguna vez a AEW? \u00bfTendremos alguna vez esa lucha con Swerve [Strickland]? Bueno, lo \u00fanico que puedo decirles es que, como saben, esto se ha comentado dentro del negocio, obviamente con esta noticia. Se ha hablado mucho de Keith Lee en los \u00faltimos d\u00edas\u201d, dijo \u00c1lvarez. \u201cNo lo afirmo con total seguridad, \u00bfde acuerdo? No lo afirmo con total seguridad porque no lo s\u00e9. Pero, por lo que he hablado con la gente, la opini\u00f3n general en el negocio es que Keith Lee se ha retirado. Y no me refiero a que, cuando termine con AEW, si es que eso llega a suceder, se vaya a otro lado; se cree que probablemente se haya retirado definitivamente\u201d.<\/p><\/blockquote>\n<h2>Keith Lee y Michin se divorciaron<\/h2>\n<p>Mia Yim (Michin en la WWE) <a href=\"https:\/\/www.prwrestling.com\/nw\/estrella-de-wwe-michin-confirma-se-divorcio-de-keith-lee\/\">public\u00f3 que se divorci\u00f3 de Lee<\/a> y, si bien ella y Lee ya no son pareja, siguen siendo amigos y se tienen mucho cari\u00f1o. Lee no ha publicado nada en redes sociales desde septiembre de 2025, el mismo mes en que tuite\u00f3 que &#8220;sin duda&#8221; volver\u00eda al ring, pero que no sab\u00eda c\u00f3mo ni cu\u00e1ndo suceder\u00eda.<\/p>\n<p>El informe m\u00e1s reciente sobre la situaci\u00f3n de Lee provino de Fightful Select , que escribi\u00f3 en junio que AEW hab\u00eda discutido un posible regreso de Lee &#8220;hace varios meses&#8221;. Sin embargo, el informe indicaba que Lee no hab\u00eda estado entre bastidores en los shows de AEW, y se desconoce si siquiera estaba al tanto de la idea de su regreso. Hasta el momento, no se ha concretado nada.<\/p>\n<p>Lee es un excampe\u00f3n de parejas de AEW junto a Swerve Strickland y ostent\u00f3 el Campeonato de NXT y el Campeonato Mundial de PWG antes de su etapa en AEW.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No hay informaci\u00f3n definitiva sobre la situaci\u00f3n de Keith Lee, pero, dentro de la industria, se cree que podr\u00eda haber disputado ya su \u00faltimo combate.<\/p>\n","protected":false},"author":3,"featured_media":160672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-291523","post","type-post","status-publish","format-standard","has-post-thumbnail","category-all-elite-wrestling"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/291523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=291523"}],"version-history":[{"count":2,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/291523\/revisions"}],"predecessor-version":[{"id":291525,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/291523\/revisions\/291525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/160672"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=291523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=291523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=291523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}