{"id":4770,"date":"2015-08-23T20:42:27","date_gmt":"2015-08-24T00:42:27","guid":{"rendered":"http:\/\/prwrestling.com\/nw\/?p=4770"},"modified":"2024-07-20T20:41:27","modified_gmt":"2024-07-21T00:41:27","slug":"resultados-de-summerslam-hasta-el-momento","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/resultados-de-summerslam-hasta-el-momento\/","title":{"rendered":"RESULTADOS WWE SUMMERSLAM 2015 &#8211; Undertaker vence a Lesnar en final controversial"},"content":{"rendered":"<p style=\"text-align: center;\"><em>Undertaker vence a Lesnar en final controversial; Rollins se corona doble campe\u00f3n.<!--more--><\/em><\/p>\n<p>El animador Jon Stewart comienza el show y dice que quiere entrevistar a Lesnar, pero necesita a alguien que lo apoye y presenta a Mick Foley. Foley le dice que se confundi\u00f3 porque pensaba que la entrevista era a Rock, no Brock y le dice que le tiene miedo a Brock. Foley le dice que ha ido a muchos lados, pero no a Suplex City y le dice a Stewart que est\u00e1 solo.<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\">\r\n<p style=\"text-align: center;\">\r\n<!-- Site name: prwrestling.com\r\nZone name: prwrestling.com_banner_300x250\r\nZone id: 2109741734\r\nType: banner\r\nFormat: 300x250\r\n --> \r\n\r\n<!-- Copy and paste this code on the page. -->\r\n<div id='zone_2109741734' ><\/div>\r\n<script>\r\n    (function(w,d,o,g,r,a,m){\r\n        var cid='zone_2109741734';\r\n        w[r]=w[r]||function(){(w[r+'l']=w[r+'l']||[]).push(arguments)};\r\n        function e(b,w,r){if((w[r+'h']=b.pop())&&!w.ABN){\r\n            var a=d.createElement(o),p=d.getElementsByTagName(o)[0];a.async=1;\r\n            a.src='https:\/\/cdn.'+w[r+'h']+'\/libs\/e.js';a.onerror=function(){e(g,w,r)};\r\n            p.parentNode.insertBefore(a,p)}}e(g,w,r);\r\n        w[r](cid,{id:2109741734,domain:w[r+'h']});\r\n    })(window,document,'script',['traffmovie.com'],'ABNS');\r\n<\/script>\r\n\r\n<!--\r\nWhen setting the zone code, make sure:\r\n  - you have provided all domains from which the area code will be called\r\n  - the site does not limit the loading in the Content Security Policy\r\n  - the area code is installed in the ad space inside the page\r\n  - site layout allows you to display the banner on mobile devices in full size\r\nUse data-cp1={customParam1} data-cp2={customParam2}... attributes for sending custom params\r\n-->\r\n<\/p><\/div><\/p>\n<p>Sheamus sobre Randy Orton tras pegale un segundo Brogue Kick.<\/p>\n<p>New Day se coronaron nuevos campeones en pareja en el 4way ante Los Matadores, The Prime Time Players, y The Lucha Dragons luego de que Kofi se roba el planche de Titus a uno de los Matadores.<\/p>\n<p>Rusev (c\/Summer Rae) vs. Dolph Ziggler (c\/Lana) termina sin ganador cuando ambos son contados fuera del ring mientras que a la vez en las afueras Lana y Summer se peleaban.<div id=\"ad-slot\" style=\"min-width: 300px; min-height: 250px;\"><p style=\"text-align: center;\">\r\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Responsive sc c -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-1244235910658811\"\r\n     data-ad-slot=\"4234005358\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/p><\/div><\/p>\n<p>Stephen Amell y Neville sobre \u00a0Stardust y King Barrett luego de que Amell hace un lance aereo sobre los rudos seguido por el Red Arrow a Barrett.<\/p>\n<p>Ryback retuvo el campeonato IC ante Miz y Big Show en lucha corta cuando Show le pega KO a Miz, Ryback lo saca del ring y cubre a Miz para la victoria.<\/p>\n<p>John Stewart va al camerino de Lesnar y Heyman le dice que supone que no pudieron conseguir a David Letterman, lo que molesta a Stewart.<\/p>\n<p>Roman Reigns y Dean Ambrose sobre Bray Wyatt y Luke Harper cuando al final todos se pelean; Wyatt le iba a pegar el Sister Abigail a Ambrose, pero este lo reversa al Dirty Deeds. Reigns luego le pega Spear a Wyatt y lo plancha para la victoria.<\/p>\n<p style=\"text-align: center;\">Contin\u00faa abajo\u00a0\u2193<br \/>\n<script type=\"text\/javascript\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- 300x250 en medio de portajes (manual placement) --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 300px; height: 250px;\" data-ad-client=\"ca-pub-1244235910658811\" data-ad-slot=\"8592682546\"><\/ins><script type=\"text\/javascript\">\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n<p>Seth Rollins se coron\u00f3 nuevo campe\u00f3n US tras vencer a John Cena en tremenda lucha en la cual Rollins le peg\u00f3 un mega Frog Splash al estilo Eddie Guererro y Cena la aplico una figura 4 en tributo a Ric Flair. Al final Cena le iba apegar AA pero le pega accidentalmente al \u00e1rbitro. Rollins luego le pega rodillazo a la nariz de Cena y los dos quedan tendidos en la lona. Sale John Stewart con silla en mano para lo que parec\u00eda pegarle a Rollins, pero sorprende y le pega con la silla al abdomen de Cena. Stewart luego coloca la silla en el ring y Rollins le pega Pedogree a Cena sobre la silla para ganar y ser el nuevo doble campe\u00f3n.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/prwrestling.com\/nw\/wp-content\/uploads\/2015\/08\/stewart.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4779 aligncenter\" src=\"http:\/\/prwrestling.com\/nw\/wp-content\/uploads\/2015\/08\/stewart.png\" alt=\"stewart\" width=\"361\" height=\"188\" srcset=\"https:\/\/www.prwrestling.com\/nw\/wp-content\/uploads\/2015\/08\/stewart.png 601w, https:\/\/www.prwrestling.com\/nw\/wp-content\/uploads\/2015\/08\/stewart-300x156.png 300w\" sizes=\"auto, (max-width: 361px) 100vw, 361px\" \/><\/a><\/p>\n<p>Paige\/Charlotte\/Becky Lynch sobre Sasha Banks\/Naomi\/Tamina y Nikki Bella\/Brie Bella\/Alicia Fox en three-way Triple Threat.\u00a0Brie elimina a Tamina para su equipo quedar fuera. Al final Becky le pega su movida final a Brie para la Victoria del Team PCB.<\/p>\n<p>Kevin Owens sobre Cesaro en tremenda lucha cuando al final Cesaro lo tiene en la tercera cuerda pero Owens causa que Cesaro caiga castrado en las cuerdas, luego le pega una suplex invertida desde las alturas seguida por el Pop-Up Powerbomb para la victoria.<\/p>\n<p>En la estelar, Undertaker sobre Brock Lesnar. Lucha en la que fueron al grano peg\u00e1ndose sus especialidades, incluyendo una F5 sobre la mesa de comentaristas y Tombstone de Undertaker. Hubo final controversial. Lesnar la aplica el candado al brazo a Undertaker y en un momento Undertaker tuvo sus hombros sobre la lona, el \u00e1rbitro hace conteo de 1 pero suenan la campana ya que hubo una supuesta confusi\u00f3n de que Undertaker se hab\u00eda rendido. Lesnar celebra pero el \u00e1rbitro decreta que la lucha continua. Taker le pega golpe bajo a Lesnar sin el \u00e1rbitro darse cuenta seguido por el Hells Gate. Lesnar trata de zafarse pero no puede y le saca el dedo del medio a Underaker hasta que es vencido.<\/p>\n<p>Luego de la lucha Undertaker se marcha y al presentar las repeticiones queda revelado que Undertaker en efecto se hab\u00eda rendido del candado al brazo de Lesnar, pero el referee no lo vio.\u00a0Paul Heyman luego toca la campana y dice que todo el mundo sabe que el ganador lo es Brock Lesnar, terminando as\u00ed el programa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Undertaker vence a Lesnar en final controversial; Rollins se corona doble campe\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":147798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[9,5394],"class_list":["post-4770","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-noticias-y-rumores-de-la-wwe","tag-wwe","tag-wwe-summerslam"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/4770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=4770"}],"version-history":[{"count":17,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/4770\/revisions"}],"predecessor-version":[{"id":4781,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/4770\/revisions\/4781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/147798"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=4770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=4770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=4770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}