{"id":876,"date":"2014-06-22T11:57:55","date_gmt":"2014-06-22T11:57:55","guid":{"rendered":"http:\/\/prwrestling.com\/nw\/?p=876"},"modified":"2014-06-22T11:57:55","modified_gmt":"2014-06-22T11:57:55","slug":"resultados-completos-wwc-summer-madness-621","status":"publish","type":"post","link":"https:\/\/www.prwrestling.com\/nw\/resultados-completos-wwc-summer-madness-621\/","title":{"rendered":"RESULTADOS COMPLETOS WWC SUMMER MADNESS 6\/21"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment-post-thumbnail alignleft\" alt=\"miguelito\" src=\"http:\/\/prwrestling.com\/nw\/wp-content\/uploads\/2014\/06\/miguelito-150x150.jpg\" width=\"150\" height=\"150\" \/>WWC presento el S\u00faper evento SUMMER MADNESS en la Cancha Jos\u00e9 \u201cPep\u00edn\u201d Cestero de Bayam\u00f3n ante aproximadamente 500 fan\u00e1ticos.<!--more--><\/p>\n<p><em>Por Junior, Forowwc.com<\/em><\/p>\n<p>La Cartelera comienza a las 9.05pm cuando sale El Wizard acompa\u00f1ado de una modelo llamada Vanessa, estos regalan camisas de Carlos Colon a las personas que contesten correctamente unas preguntas. Luego el Wizard anuncia que por compromisos previos Carlito Caribbean Cool no estar\u00e1 presente esta noche en Summer Madness , luego sale TNT e insulta a Carlito llam\u00e1ndolo tecato y que le tiene miedo, a lo que entra El Le\u00f3n Apolo y reta a TNT a una lucha esta misma noche. TNT se va a los camerinos y cuando Apolo se va a los camerinos es atacado por TNT que lo castiga con el Campeonato de P.R.<\/p>\n<p>Primera lucha:<br \/>\nChicano sobre The Alien por descalificaci\u00f3n, cuando The Alien se pone un objeto en la m\u00e1scara, se trepa a la segunda cuerda y castiga a Chicano, luego lo cubre para el conteo de tres, pero en eso entra Mike Mendoza y le explica al \u00e1rbitro lo sucedido y cuando el \u00e1rbitro va donde The Alien lo ve quit\u00e1ndose el objeto de la m\u00e1scara y revoca la decisi\u00f3n, declarando ganador a Chicano.<\/p>\n<p>Segunda lucha:<br \/>\nJos\u00e9 Chaparro sobre Chicky Starr con la ayuda de Juan Manuel Ortega.<\/p>\n<p>Tercera Lucha:<br \/>\nEl Le\u00f3n Apolo sobre TNT en lucha NO titular.<\/p>\n<p>Cuarta Lucha:<br \/>\nRikochet sobre Tommy Diablo, para convertirse en el primer retador al Campeonato Mundial Jr. Completo.<\/p>\n<p>Quinta Lucha: Por el Campeonato Mundial Jr. Completo<br \/>\nMike Mendoza sobre \u00c1ngel Fashion P\u00e9rez para convertirse por primera vez Campe\u00f3n Mundial Jr. Completo.<\/p>\n<p>Sexta Lucha:<br \/>\nAndy Leavine sobre Xix Xavant.<\/p>\n<p>Receso<\/p>\n<p>S\u00e9ptima Lucha: Por El Campeonato Universal<br \/>\nRay Gonz\u00e1lez (con Chicky Starr en su esquina) sobre Mighty Ursus (con Jos\u00e9 Chaparro en su esquina), cuando en los momentos finales, Chaparro se trepa en la faldeta del ring y es castigado por Chicky Starr con el bate, luego Mighty Ursus agarra por la cabeza a Chicky Starr y este le mete con el bate por la cabeza, lo que aprovecha Ray Gonzalez para aplicarle el vuelo del f\u00e9nix a Ursus, cuando el conteo va por dos, Chaparro hala al \u00e1rbitro por la pierna cayendo este al piso, lo que aprovecha Mighty Ursus para aplicarle a Ray una Power Bomb y luego un sent\u00f3n desde la segunda cuerda, lo cubre y entra otro arbitro y hace el conteo declarando nuevo Campeon Universal a Mighty Ursus, pero el \u00e1rbitro principal de la lucha, le dice al otro arbitro que Chaparro lo halo por la pierna y revoca la decisi\u00f3n y declara ganador a Ray Gonzalez, Ursus y Ray se van a golpe limpio a los camerinos y se quedan cara a cara Chicky Starr y Chaparro, pero por la espalda entra Juan Manuel Ortega y le da golpe bajo a Chicky, y junto a Chaparro castigan a Chicky hasta que los \u00e1rbitros los separan. Cuando Chaparro se dirig\u00eda al camerino discute con la esposa de Chicky que estaba en el p\u00fablico, luego Chaparro la empuja, lo que causa que Chicky Starr salga como un loco y le entre a batazos a Chaparro y a Ortega. Luego Chicky casi llorando le dice a Chaparro que no se meta con su familia, Chicky se da en la cara y amenaza a Chaparro.<\/p>\n<p>Octava lucha: Por los Campeonato Mundiales en parejas<br \/>\nLos Boricuas sobre Los Templarios para coronarse nuevos Campeones Mundiales en Parejas. Luego de la lucha Ash coge el micr\u00f3fono y dice que le ganaron con trampa, porque el, levanto el hombro al conteo de dos, pero que quiere la revancha ahora mismo, Huracan castillo coge el micr\u00f3fono y le dice que si Ash quiere la revancha, lo tiene que derrotar a \u00e9l, a lo que Ash acepta y se van a los camerinos.<\/p>\n<p>Anuncian que el pr\u00f3ximo s\u00e1bado estar\u00e1n en el Coliseo Cosme Beitia S\u00e1lamo de Cata\u00f1o. Terminando as\u00ed, Summer Madness.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WWC presento el S\u00faper evento SUMMER MADNESS en la Cancha Jos\u00e9 \u201cPep\u00edn\u201d Cestero de Bayam\u00f3n ante aproximadamente 500 fan\u00e1ticos.<\/p>\n","protected":false},"author":1,"featured_media":811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-876","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/comments?post=876"}],"version-history":[{"count":1,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/876\/revisions"}],"predecessor-version":[{"id":877,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/posts\/876\/revisions\/877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media\/811"}],"wp:attachment":[{"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/media?parent=876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/categories?post=876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prwrestling.com\/nw\/wp-json\/wp\/v2\/tags?post=876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}